{"id":14159,"date":"2025-05-21T10:44:21","date_gmt":"2025-05-21T13:44:21","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=14159"},"modified":"2025-05-21T11:01:32","modified_gmt":"2025-05-21T14:01:32","slug":"pintores-caem-de-torre-de-igreja-em-tres-pontas-um-morre-e-outro-e-socorrido","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/pintores-caem-de-torre-de-igreja-em-tres-pontas-um-morre-e-outro-e-socorrido\/","title":{"rendered":"Pintores caem de torre de igreja em Tr\u00eas Pontas; um morre e outro \u00e9 socorrido"},"content":{"rendered":"<p>Dois pintores ca\u00edram da torre da Igreja Nossa Senhora Aparecida, em Tr\u00eas Pontas (MG), na manh\u00e3 desta quarta-feira (21). Segundo as primeiras informa\u00e7\u00f5es, Vivaldi Marcelino, um dos trabalhadores, n\u00e3o resistiu aos ferimentos e morreu no local. O outro foi socorrido em estado grave at\u00e9 o Pronto Atendimento Municipal.<\/p>\n<p>A Pol\u00edcia Militar isolou a \u00e1rea e a per\u00edcia da Pol\u00edcia Civil foi acionada para investigar as causas do acidente.<\/p>\n<p>TPOWER &#8211; @portaltpower<br \/>\nConectado na not\u00edcia!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois pintores ca\u00edram da torre da Igreja Nossa Senhora Aparecida, em Tr\u00eas Pontas (MG), na manh\u00e3 desta quarta-feira (21). Segundo as primeiras informa\u00e7\u00f5es, Vivaldi Marcelino, um dos trabalhadores, n\u00e3o resistiu aos ferimentos e morreu no local. O outro foi socorrido em estado grave at\u00e9 o Pronto Atendimento Municipal. A Pol\u00edcia Militar isolou a \u00e1rea e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14160,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/14159"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=14159"}],"version-history":[{"count":2,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/14159\/revisions"}],"predecessor-version":[{"id":14162,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/14159\/revisions\/14162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/14160"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=14159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=14159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=14159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}