{"id":15271,"date":"2025-06-24T06:35:27","date_gmt":"2025-06-24T09:35:27","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=15271"},"modified":"2025-06-24T06:35:55","modified_gmt":"2025-06-24T09:35:55","slug":"palmeiras-empata-com-inter-miami-e-avanca-para-confronto-brasileiro-nas-oitavas-do-mundial-de-clubes","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/palmeiras-empata-com-inter-miami-e-avanca-para-confronto-brasileiro-nas-oitavas-do-mundial-de-clubes\/","title":{"rendered":"Palmeiras empata com Inter Miami e avan\u00e7a para confronto brasileiro nas oitavas do Mundial de Clubes; assista os melhores momentos"},"content":{"rendered":"<p>Em uma partida eletrizante realizada nesta segunda-feira (23), no Hard Rock Stadium, em Miami, o Palmeiras empatou por 2 a 2 com o Inter Miami e garantiu a lideran\u00e7a do Grupo A do Mundial de Clubes. Com o resultado, o Verd\u00e3o se classificou para as oitavas de final e enfrentar\u00e1 o Botafogo em um confronto nacional decisivo.<\/p>\n<p>O time norte-americano saiu na frente com gols de Tadeo Allende e Luis Su\u00e1rez, ainda no primeiro tempo. No entanto, o Palmeiras reagiu na etapa final. Paulinho diminuiu aos 35 minutos, e Maur\u00edcio, aos 42, marcou o gol do empate, que garantiu a primeira coloca\u00e7\u00e3o para a equipe brasileira, superando o Inter Miami no saldo de gols.<\/p>\n<p>Com a lideran\u00e7a assegurada, o Palmeiras ter\u00e1 pela frente o Botafogo, segundo colocado do Grupo B, em um duelo marcado para o pr\u00f3ximo s\u00e1bado (28), \u00e0s 13h (hor\u00e1rio de Bras\u00edlia), no Lincoln Financial Field, na Filad\u00e9lfia. J\u00e1 o Inter Miami, liderado por Lionel Messi e Luis Su\u00e1rez, enfrentar\u00e1 o Paris Saint-Germain no domingo (29), tamb\u00e9m pelas oitavas de final.<\/p>\n<p>\ud83d\udcf2<a href=\"https:\/\/chat.whatsapp.com\/IXTyp0sB59a3cb4ahw7xBP\">Clique aqui para entrar no grupo de WhatsApp do tpower<\/a><\/p>\n<p>\ud83d\udcf8 <a href=\"https:\/\/www.instagram.com\/portaltpower\">Siga o tpower no Instagram<\/a><\/p>\n<p>Com quatro equipes brasileiras nas oitavas \u2014 Palmeiras, Botafogo, Flamengo e Fluminense \u2014 o Brasil se destaca como a principal for\u00e7a sul-americana da competi\u00e7\u00e3o. O Flamengo aguarda o segundo colocado do Grupo C, enquanto o Fluminense tamb\u00e9m est\u00e1 classificado, com seu advers\u00e1rio ainda indefinido.<\/p>\n<p>tpower \u2013 <a href=\"https:\/\/www.instagram.com\/portaltpower\">@portaltpower<\/a><br \/>\nConectado na not\u00edcia!<\/p>\n<p>Melhores momentos:<\/p>\n<div style=\"position: relative; width: 100%; padding-bottom: 56.25%; height: 0; overflow: hidden; max-width: 600px; margin: 0 auto;\"><iframe style=\"position: absolute; top: 0; left: 0; width: 100%; height: 100%;\" src=\"https:\/\/www.youtube.com\/embed\/R3-04hRwi50\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Em uma partida eletrizante realizada nesta segunda-feira (23), no Hard Rock Stadium, em Miami, o Palmeiras empatou por 2 a 2 com o Inter Miami e garantiu a lideran\u00e7a do Grupo A do Mundial de Clubes. Com o resultado, o Verd\u00e3o se classificou para as oitavas de final e enfrentar\u00e1 o Botafogo em um confronto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15272,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[103],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/15271"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=15271"}],"version-history":[{"count":2,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/15271\/revisions"}],"predecessor-version":[{"id":15274,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/15271\/revisions\/15274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/15272"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=15271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=15271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=15271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}