{"id":16815,"date":"2025-08-13T16:07:33","date_gmt":"2025-08-13T19:07:33","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=16815"},"modified":"2025-08-13T16:07:33","modified_gmt":"2025-08-13T19:07:33","slug":"idosos-de-paraguacu-participam-de-festa-agostina-em-cabo-verde","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/idosos-de-paraguacu-participam-de-festa-agostina-em-cabo-verde\/","title":{"rendered":"Idosos de Paragua\u00e7u participam de Festa Agostina em Cabo Verde"},"content":{"rendered":"<p>Nesta quarta-feira (13), o poliesportivo de Cabo Verde foi palco de um encontro marcado por alegria e integra\u00e7\u00e3o. A cidade recebeu a Festa Agostina, evento que reuniu idosos de Cabo Verde, Botelhos, Campestre e Paragua\u00e7u em uma programa\u00e7\u00e3o especial que uniu o clima tradicional das festas juninas com o encanto da primavera.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-16817 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/www.tpower.com.br\/site\/wp-content\/uploads\/2025\/08\/083dc6fd-db0f-4527-8c20-2ac0c58ea6dd-300x214.jpeg\" alt=\"\" width=\"300\" height=\"214\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.tpower.com.br\/site\/wp-content\/uploads\/2025\/08\/083dc6fd-db0f-4527-8c20-2ac0c58ea6dd-300x214.jpeg 300w, https:\/\/www.tpower.com.br\/site\/wp-content\/uploads\/2025\/08\/083dc6fd-db0f-4527-8c20-2ac0c58ea6dd-768x547.jpeg 768w, https:\/\/www.tpower.com.br\/site\/wp-content\/uploads\/2025\/08\/083dc6fd-db0f-4527-8c20-2ac0c58ea6dd-600x427.jpeg 600w, https:\/\/www.tpower.com.br\/site\/wp-content\/uploads\/2025\/08\/083dc6fd-db0f-4527-8c20-2ac0c58ea6dd-20x14.jpeg 20w, https:\/\/www.tpower.com.br\/site\/wp-content\/uploads\/2025\/08\/083dc6fd-db0f-4527-8c20-2ac0c58ea6dd.jpeg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>De Paragua\u00e7u, participaram 161 idosos do Centro Municipal de Conviv\u00eancia do Idoso. Eles viajaram em tr\u00eas \u00f4nibus, uma van e um carro de apoio para aproveitar um dia repleto de m\u00fasica, dan\u00e7a, comidas t\u00edpicas e momentos de descontra\u00e7\u00e3o.<\/p>\n<p>\ud83d\udcf8 <a href=\"https:\/\/www.instagram.com\/portaltpower\">Siga o tpower no Instagram<\/a><\/p>\n<p>\ud83d\udcf2<a href=\"https:\/\/chat.whatsapp.com\/IXTyp0sB59a3cb4ahw7xBP\">Clique aqui para entrar no grupo de WhatsApp do tpower<\/a><\/p>\n<p>A iniciativa promoveu a socializa\u00e7\u00e3o entre grupos de diferentes cidades e proporcionou aos participantes um ambiente acolhedor, com direito a muita anima\u00e7\u00e3o e intera\u00e7\u00e3o entre amigos.<\/p>\n<p>tpower &#8211; <a href=\"https:\/\/www.instagram.com\/portaltpower\">@portaltpower<\/a><br \/>\nConectado na not\u00edcia!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira (13), o poliesportivo de Cabo Verde foi palco de um encontro marcado por alegria e integra\u00e7\u00e3o. A cidade recebeu a Festa Agostina, evento que reuniu idosos de Cabo Verde, Botelhos, Campestre e Paragua\u00e7u em uma programa\u00e7\u00e3o especial que uniu o clima tradicional das festas juninas com o encanto da primavera. De Paragua\u00e7u, participaram [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16816,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[344,343,115,345],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/16815"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=16815"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/16815\/revisions"}],"predecessor-version":[{"id":16818,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/16815\/revisions\/16818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/16816"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=16815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=16815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=16815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}