{"id":16931,"date":"2025-08-16T10:34:53","date_gmt":"2025-08-16T13:34:53","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=16931"},"modified":"2025-08-16T10:37:14","modified_gmt":"2025-08-16T13:37:14","slug":"acidente-em-diadema-perseguicao-a-ladroes-termina-em-morte-de-motociclista","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/acidente-em-diadema-perseguicao-a-ladroes-termina-em-morte-de-motociclista\/","title":{"rendered":"Acidente em Diadema: persegui\u00e7\u00e3o a ladr\u00f5es termina em morte de motociclista"},"content":{"rendered":"<p>Na madrugada deste s\u00e1bado (16), um caminh\u00e3o de uma empresa de colch\u00f5es foi perseguido por dois ladr\u00f5es em uma moto na avenida Rio de Janeiro, em Diadema (SP). Durante a fuga, o motorista do caminh\u00e3o tentou derrubar os suspeitos e atingiu a moto deles.<\/p>\n<p>\ud83d\udcf8 <a href=\"https:\/\/www.instagram.com\/portaltpower\">Siga o tpower no Instagram<\/a><\/p>\n<p>\ud83d\udcf2 <a href=\"https:\/\/chat.whatsapp.com\/IXTyp0sB59a3cb4ahw7xBP\">Clique aqui para entrar no grupo de WhatsApp do tpower<\/a><\/p>\n<p>No entanto, o ve\u00edculo invadiu a contram\u00e3o e colidiu com um jovem casal. O motociclista morreu no local, enquanto sua esposa, gr\u00e1vida de quatro meses, foi socorrida e levada ao Hospital de Diadema.<\/p>\n<p>Os dois criminosos roubaram outra moto e conseguiram fugir. At\u00e9 o momento, n\u00e3o foram localizados pela pol\u00edcia.<\/p>\n<p>tpower \u2013 @portaltpower<br \/>\nConectado na not\u00edcia!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na madrugada deste s\u00e1bado (16), um caminh\u00e3o de uma empresa de colch\u00f5es foi perseguido por dois ladr\u00f5es em uma moto na avenida Rio de Janeiro, em Diadema (SP). Durante a fuga, o motorista do caminh\u00e3o tentou derrubar os suspeitos e atingiu a moto deles. \ud83d\udcf8 Siga o tpower no Instagram \ud83d\udcf2 Clique aqui para entrar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16932,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[297,101],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/16931"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=16931"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/16931\/revisions"}],"predecessor-version":[{"id":16933,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/16931\/revisions\/16933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/16932"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=16931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=16931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=16931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}