{"id":18252,"date":"2025-10-02T15:19:34","date_gmt":"2025-10-02T18:19:34","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=18252"},"modified":"2025-10-02T15:19:34","modified_gmt":"2025-10-02T18:19:34","slug":"homem-persegue-e-joga-moto-contra-irmao","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/homem-persegue-e-joga-moto-contra-irmao\/","title":{"rendered":"Homem persegue e joga moto contra irm\u00e3o"},"content":{"rendered":"<p>Um homem \u00e9 investigado pela Pol\u00edcia Civil ap\u00f3s provocar um acidente intencional contra o pr\u00f3prio irm\u00e3o em Uberl\u00e2ndia, no Tri\u00e2ngulo Mineiro. O caso ocorreu no Bairro Jardim das Palmeiras, e foi registrado como tentativa de h0mic\u00eddlo.<\/p>\n<p>Imagens de c\u00e2meras de monitoramento mostram o momento em que o suspeito invade a contram\u00e3o, acelera em dire\u00e7\u00e3o ao irm\u00e3o e salta da motocicleta instantes antes da batida.<\/p>\n<p>Segundo relato da v\u00edtima, de 35 anos, o suspeito a perseguiu desde a sa\u00edda de casa at\u00e9 a escola da filha, de 11 anos. A colis\u00e3o aconteceu quando ele retornava para casa. A Pol\u00edcia Civil informou que a motiva\u00e7\u00e3o para o crime ainda est\u00e1 sendo apurada.<\/p>\n<p>Ainda conforme a v\u00edtima, o suspeito possui diversas passagens policiais e chegou a ser alvo de medida protetiva solicitada pela m\u00e3e. O Corpo de Bombeiros foi acionado, mas a v\u00edtima acabou sendo socorrida por testemunhas antes da chegada do resgate.<\/p>\n<p>Ap\u00f3s atendimento m\u00e9dico, o homem recebeu afastamento de 15 dias das atividades em raz\u00e3o de les\u00f5es na perna direita. O suspeito n\u00e3o foi localizado e segue sendo procurado pela pol\u00edcia.<\/p>\n<div style=\"position: relative; width: 100%; padding-bottom: 125%; height: 0; overflow: hidden; max-width: 500px; margin: 0 auto;\"><iframe style=\"position: absolute; top: 0; left: 0; width: 100%; height: 100%;\" src=\"https:\/\/www.instagram.com\/reel\/DPUNj4SjTxk\/embed\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um homem \u00e9 investigado pela Pol\u00edcia Civil ap\u00f3s provocar um acidente intencional contra o pr\u00f3prio irm\u00e3o em Uberl\u00e2ndia, no Tri\u00e2ngulo Mineiro. O caso ocorreu no Bairro Jardim das Palmeiras, e foi registrado como tentativa de h0mic\u00eddlo. Imagens de c\u00e2meras de monitoramento mostram o momento em que o suspeito invade a contram\u00e3o, acelera em dire\u00e7\u00e3o ao [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18253,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[101,321],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/18252"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=18252"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/18252\/revisions"}],"predecessor-version":[{"id":18254,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/18252\/revisions\/18254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/18253"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=18252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=18252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=18252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}