{"id":18990,"date":"2025-11-07T18:01:20","date_gmt":"2025-11-07T21:01:20","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=18990"},"modified":"2025-11-07T18:01:20","modified_gmt":"2025-11-07T21:01:20","slug":"confira-como-ficou-a-cotacao-do-cafe-nesta-sexta-feira-7","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/confira-como-ficou-a-cotacao-do-cafe-nesta-sexta-feira-7\/","title":{"rendered":"Confira como ficou a cota\u00e7\u00e3o do caf\u00e9 nesta sexta-feira (7)"},"content":{"rendered":"<p>De acordo com o Centro do Com\u00e9rcio de Caf\u00e9 de Minas Gerais (CCCMG), o mercado se manteve calmo nesta sexta-feira (7). Na B3, em S\u00e3o Paulo, o contrato para mar\u00e7o de 2026 fechou em US$ 476,80 por saca, registrando alta de +10,25. J\u00e1 na Bolsa de Nova York, o mesmo vencimento foi cotado a US\u00a2 385,85 por libra-peso, com avan\u00e7o de +6,80.<\/p>\n<p>O d\u00f3lar Ptax de compra foi cotado a US$ 5,3561, com leve varia\u00e7\u00e3o positiva de +0,22%.<\/p>\n<p>\ud83d\udcf2<a href=\"https:\/\/chat.whatsapp.com\/IXTyp0sB59a3cb4ahw7xBP\">Clique aqui para entrar no grupo de WhatsApp do tpower<\/a><\/p>\n<p>\ud83d\udcf8 <a href=\"https:\/\/www.instagram.com\/portaltpower\">Siga o tpower no Instagram<\/a><\/p>\n<p>Confira os pre\u00e7os m\u00e9dios apurados nas pra\u00e7as cafeeiras do Sul de Minas:<\/p>\n<p>\u2022 Tipo 6 bebida dura \u2013 R$ 2.301,00<\/p>\n<p>\u2022 Tipo 7 bebida dura \u2013 R$ 2.234,00<\/p>\n<p>\u2022 Tipo 6 bebida riada \u2013 R$ 1.980,00<\/p>\n<p>\u2022 Tipo 7 bebida rio \u2013 R$ 1.562,00<\/p>\n<p>Os valores s\u00e3o referentes a caf\u00e9s tipo bica corrida ar\u00e1bica, livres de impostos, para sacas de 60 kg.<\/p>\n<p>tpower &#8211; <a href=\"https:\/\/www.instagram.com\/portaltpower\">@portaltpower<\/a><br \/>\nConectado na not\u00edcia!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com o Centro do Com\u00e9rcio de Caf\u00e9 de Minas Gerais (CCCMG), o mercado se manteve calmo nesta sexta-feira (7). Na B3, em S\u00e3o Paulo, o contrato para mar\u00e7o de 2026 fechou em US$ 476,80 por saca, registrando alta de +10,25. J\u00e1 na Bolsa de Nova York, o mesmo vencimento foi cotado a US\u00a2 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12831,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[65],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/18990"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=18990"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/18990\/revisions"}],"predecessor-version":[{"id":18991,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/18990\/revisions\/18991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/12831"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=18990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=18990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=18990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}