{"id":19038,"date":"2025-11-13T07:54:47","date_gmt":"2025-11-13T10:54:47","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=19038"},"modified":"2025-11-13T07:54:47","modified_gmt":"2025-11-13T10:54:47","slug":"operacao-desarticula-rede-de-venda-de-medicamentos-falsificados-pela-internet-no-sul-de-minas-e-em-sp","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/operacao-desarticula-rede-de-venda-de-medicamentos-falsificados-pela-internet-no-sul-de-minas-e-em-sp\/","title":{"rendered":"Opera\u00e7\u00e3o desarticula rede de venda de medicamentos falsificados pela internet no Sul de Minas e em SP"},"content":{"rendered":"<p>Uma opera\u00e7\u00e3o realizada com apoio do 64\u00ba Batalh\u00e3o da Pol\u00edcia Militar de Minas Gerais (PMMG) desmantelou um esquema de comercializa\u00e7\u00e3o de medicamentos falsificados pela internet. A a\u00e7\u00e3o cumpriu 19 mandados de busca e apreens\u00e3o em Campo do Meio, Boa Esperan\u00e7a, Campo Belo e Ribeir\u00e3o Preto (SP), expedidos pela 2\u00aa Vara Criminal de Campos Gerais.<\/p>\n<p>Quatro pessoas foram presas em flagrante, e entre os materiais apreendidos estavam celulares, notebooks, sete muni\u00e7\u00f5es calibre 32, cerca de R$ 11 mil em esp\u00e9cie, 3,9 mil comprimidos, 164 seringas de enoxaparina e diversas embalagens de medicamentos e xampus dermatol\u00f3gicos.<\/p>\n<p>@portaltpower Conectado na not\u00edcia!<\/p>\n<p>As investiga\u00e7\u00f5es revelaram que o grupo mantinha uma estrutura log\u00edstica compartilhada, usava m\u00e9todos de contrafa\u00e7\u00e3o dispersos e criava v\u00e1rias contas em plataformas de e-commerce em nome de terceiros para ocultar a verdadeira propriedade das lojas e os lucros il\u00edcitos. Foram identificadas 40 lojas virtuais ligadas \u00e0 organiza\u00e7\u00e3o, com mais de 10 mil vendas de produtos falsificados, incluindo verm\u00edfugos, antipulgas, xampus para animais e at\u00e9 comprimidos usados para disfun\u00e7\u00e3o er\u00e9til.<\/p>\n<p>\ud83d\udcf2<a href=\"https:\/\/chat.whatsapp.com\/IXTyp0sB59a3cb4ahw7xBP\">Clique aqui para entrar no grupo de WhatsApp do tpower<\/a><\/p>\n<p>Segundo a apura\u00e7\u00e3o, os produtos eram vendidos at\u00e9 30% abaixo do pre\u00e7o de mercado e enviados para consumidores em mais de 20 estados brasileiros.<\/p>\n<p>\ud83d\udcf8 <a href=\"https:\/\/www.instagram.com\/portaltpower\">Siga o tpower no Instagram<\/a><\/p>\n<p>A opera\u00e7\u00e3o contou com a participa\u00e7\u00e3o de quatro promotores de Justi\u00e7a, 92 policiais militares, al\u00e9m do apoio do Gaeco de Varginha, do Minist\u00e9rio P\u00fablico de S\u00e3o Paulo (Gaeco Ribeir\u00e3o Preto) e de um helic\u00f3ptero da 6\u00aa Base Regional de Avia\u00e7\u00e3o do Estado de Minas Gerais, da PMMG.<\/p>\n<p>tpower &#8211; <a href=\"https:\/\/www.instagram.com\/portaltpower\">@portaltpower<\/a><br \/>\nConectado na not\u00edcia!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma opera\u00e7\u00e3o realizada com apoio do 64\u00ba Batalh\u00e3o da Pol\u00edcia Militar de Minas Gerais (PMMG) desmantelou um esquema de comercializa\u00e7\u00e3o de medicamentos falsificados pela internet. A a\u00e7\u00e3o cumpriu 19 mandados de busca e apreens\u00e3o em Campo do Meio, Boa Esperan\u00e7a, Campo Belo e Ribeir\u00e3o Preto (SP), expedidos pela 2\u00aa Vara Criminal de Campos Gerais. Quatro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19039,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,47],"tags":[129],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/19038"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=19038"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/19038\/revisions"}],"predecessor-version":[{"id":19040,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/19038\/revisions\/19040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/19039"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=19038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=19038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=19038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}