{"id":19075,"date":"2025-11-14T17:20:08","date_gmt":"2025-11-14T20:20:08","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=19075"},"modified":"2025-11-14T17:20:08","modified_gmt":"2025-11-14T20:20:08","slug":"final-de-semana-sera-marcado-por-avanco-de-frente-fria","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/final-de-semana-sera-marcado-por-avanco-de-frente-fria\/","title":{"rendered":"Final de semana ser\u00e1 marcado por avan\u00e7o de frente fria"},"content":{"rendered":"<p>A aproxima\u00e7\u00e3o de uma frente fria deve mudar o tempo na regi\u00e3o. Em Paragua\u00e7u, no s\u00e1bado (15) a previs\u00e3o indica sol entre muitas nuvens e per\u00edodos de c\u00e9u nublado, com possibilidade de pancadas de chuva \u00e0 noite. As temperaturas variam entre 20\u00b0C e 27\u00b0C, com probabilidade de precipita\u00e7\u00e3o em 87%. A umidade relativa do ar oscila de 58% a 92%, e os ventos chegam a 5 km\/h, soprando de SSE. A lua segue na fase minguante.<\/p>\n<p>@portaltpower &#8211; Conectado na not\u00edcia!<\/p>\n<p>No domingo (16), o cen\u00e1rio permanece inst\u00e1vel. O dia ser\u00e1 marcado por sol com muitas nuvens e previs\u00e3o de pancadas de chuva \u00e0 tarde e \u00e0 noite. As temperaturas ficam entre 19\u00b0C e 27\u00b0C, e a chance de chuva atinge 81%. A umidade varia entre 64% e 94%, com ventos de 7 km\/h vindos do leste.<\/p>\n<p>J\u00e1 no in\u00edcio da semana, a segunda-feira (17) segue com tempo inst\u00e1vel. O dia ter\u00e1 sol com algumas nuvens e possibilidade de chuva r\u00e1pida tanto durante o dia quanto \u00e0 noite. As temperaturas variam entre 21\u00b0C e 28\u00b0C, com probabilidade de chuva em 78% e umidade entre 63% e 90%.<\/p>\n<p>Previs\u00e3o para cidades da regi\u00e3o:<\/p>\n<p>El\u00f3i Mendes: varia\u00e7\u00e3o entre 19\u00b0C e 27\u00b0C, com chance de chuva.<\/p>\n<p>Machado: temperaturas entre 18\u00b0C e 26\u00b0C e previs\u00e3o de instabilidade.<\/p>\n<p>Alfenas: m\u00e1ximas de 27\u00b0C, com possibilidade de pancadas de chuva.<\/p>\n<p>Guaxup\u00e9: tempo nublado, com chuva isolada e m\u00ednima de 18\u00b0C.<\/p>\n<p>Po\u00e7os de Caldas: clima mais ameno, entre 15\u00b0C e 23\u00b0C, com chance de garoa e pancadas de chuva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A aproxima\u00e7\u00e3o de uma frente fria deve mudar o tempo na regi\u00e3o. Em Paragua\u00e7u, no s\u00e1bado (15) a previs\u00e3o indica sol entre muitas nuvens e per\u00edodos de c\u00e9u nublado, com possibilidade de pancadas de chuva \u00e0 noite. As temperaturas variam entre 20\u00b0C e 27\u00b0C, com probabilidade de precipita\u00e7\u00e3o em 87%. A umidade relativa do ar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,47],"tags":[223,165],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/19075"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=19075"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/19075\/revisions"}],"predecessor-version":[{"id":19077,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/19075\/revisions\/19077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/19076"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=19075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=19075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=19075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}