{"id":19620,"date":"2026-01-07T12:02:07","date_gmt":"2026-01-07T15:02:07","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=19620"},"modified":"2026-01-07T12:02:07","modified_gmt":"2026-01-07T15:02:07","slug":"mst-avalia-protestos-e-possivel-envio-de-militantes-a-venezuela-apos-acao-dos-estados-unidos","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/mst-avalia-protestos-e-possivel-envio-de-militantes-a-venezuela-apos-acao-dos-estados-unidos\/","title":{"rendered":"MST avalia protestos e poss\u00edvel envio de militantes \u00e0 Venezuela ap\u00f3s a\u00e7\u00e3o dos Estados Unidos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>O Movimento dos Trabalhadores Rurais Sem Terra (MST) afirmou que n\u00e3o descarta o envio de militantes \u00e0 Venezuela ap\u00f3s o ataque dos Estados Unidos no \u00faltimo s\u00e1bado (3\/1). O tema foi discutido em uma reuni\u00e3o online no domingo (4\/1), que reuniu mais de 50 organiza\u00e7\u00f5es da esquerda brasileira.<\/p>\n<p>A a\u00e7\u00e3o militar resultou na captura de Nicol\u00e1s Maduro, levado para Nova York para julgamento por suposta conspira\u00e7\u00e3o com cart\u00e9is de drogas. Em audi\u00eancia, Maduro e sua esposa, Cilia Flores, negaram as acusa\u00e7\u00f5es. O venezuelano declarou ser um \u201cpresidente sequestrado\u201d.<\/p>\n<p>Siga o @portaltpower e continue recebendo as nossas not\u00edcias!<\/p>\n<p>Segundo participantes, ainda n\u00e3o h\u00e1 um entendimento profundo sobre o cen\u00e1rio venezuelano, considerado em desenvolvimento. Mesmo assim, o grupo deliberou a realiza\u00e7\u00e3o de manifesta\u00e7\u00f5es em v\u00e1rias capitais brasileiras, muitas delas em frente a embaixadas e consulados dos Estados Unidos.<\/p>\n<p>A dirigente do MST, Ceres Hadich, afirmou que os atos devem se estender a todas as capitais e integrar as mobiliza\u00e7\u00f5es previstas para 8 de janeiro. Ela destacou que o movimento mant\u00e9m rela\u00e7\u00f5es p\u00fablicas de solidariedade com a Venezuela e, neste momento, foca na den\u00fancia do que classifica como invas\u00e3o e sequestro promovidos pelo governo norte-americano.<\/p>\n<p>Siga o @portaltpower<br \/>\nConectado na not\u00edcia!<\/p>\n<p>#mst #venezuela #eua #politica #portaltpower<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O Movimento dos Trabalhadores Rurais Sem Terra (MST) afirmou que n\u00e3o descarta o envio de militantes \u00e0 Venezuela ap\u00f3s o ataque dos Estados Unidos no \u00faltimo s\u00e1bado (3\/1). O tema foi discutido em uma reuni\u00e3o online no domingo (4\/1), que reuniu mais de 50 organiza\u00e7\u00f5es da esquerda brasileira. A a\u00e7\u00e3o militar resultou na captura [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19621,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/19620"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=19620"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/19620\/revisions"}],"predecessor-version":[{"id":19622,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/19620\/revisions\/19622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/19621"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=19620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=19620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=19620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}