{"id":20636,"date":"2026-03-04T08:02:10","date_gmt":"2026-03-04T11:02:10","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=20636"},"modified":"2026-03-04T08:02:10","modified_gmt":"2026-03-04T11:02:10","slug":"paraguacu-sedia-treinamento-da-epr-vias-do-cafe-voltado-a-manejo-de-animais-nas-rodovias","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/paraguacu-sedia-treinamento-da-epr-vias-do-cafe-voltado-a-manejo-de-animais-nas-rodovias\/","title":{"rendered":"Paragua\u00e7u sedia treinamento da EPR Vias do Caf\u00e9 voltado \u00e0 manejo de animais nas rodovias"},"content":{"rendered":"<p>Uma capacita\u00e7\u00e3o voltada ao manejo seguro de animais de grande porte foi realizada na ter\u00e7a-feira (3) em Paragua\u00e7u. A a\u00e7\u00e3o foi promovida pela EPR Vias do Caf\u00e9 e reuniu equipes operacionais respons\u00e1veis pelos atendimentos nas rodovias administradas pela concession\u00e1ria.<\/p>\n<p>Continue recebendo mais not\u00edcias como est\u00e1! Siga o Portal tpower.<\/p>\n<p>O treinamento ocorreu em um centro veterin\u00e1rio parceiro que recebe animais recolhidos nas estradas. Ao todo, 25 colaboradores participaram da atividade, que abordou t\u00e9cnicas de laceamento e captura, tipos de n\u00f3s, uso de equipamentos de conten\u00e7\u00e3o e procedimentos adequados para lidar com bovinos e equinos encontrados \u00e0s margens das rodovias.<\/p>\n<p>De acordo com o coordenador de opera\u00e7\u00f5es da EPR Vias do Caf\u00e9, Marco Polo Clemente, a iniciativa busca refor\u00e7ar os protocolos de seguran\u00e7a adotados pelas equipes. \u201cCom essa iniciativa, refor\u00e7amos os melhores protocolos de seguran\u00e7a e manejo de animais entre nossas equipes. Atuamos para garantir um atendimento \u00e1gil e eficaz, diminuindo os riscos causados pela presen\u00e7a de animais nas rodovias. Al\u00e9m de melhorar a experi\u00eancia do usu\u00e1rio, \u00e9 mais uma a\u00e7\u00e3o para prevenir acidentes e salvar vidas\u201d, afirmou.<\/p>\n<p>O recolhimento de animais de grande porte faz parte dos servi\u00e7os operacionais da concession\u00e1ria e pode ser solicitado a qualquer momento pelo telefone 0800 265 0491.<\/p>\n<p>A concession\u00e1ria orienta que, ao avistar animais na pista ou \u00e0s margens da rodovia, o motorista reduza a velocidade, mantenha dist\u00e2ncia segura, evite buzinar para n\u00e3o assustar o animal e n\u00e3o des\u00e7a do ve\u00edculo nem tente afugent\u00e1-lo.<\/p>\n<p>tpower &#8211; @portaltpower<br \/>\nConectado na not\u00edcia!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma capacita\u00e7\u00e3o voltada ao manejo seguro de animais de grande porte foi realizada na ter\u00e7a-feira (3) em Paragua\u00e7u. A a\u00e7\u00e3o foi promovida pela EPR Vias do Caf\u00e9 e reuniu equipes operacionais respons\u00e1veis pelos atendimentos nas rodovias administradas pela concession\u00e1ria. Continue recebendo mais not\u00edcias como est\u00e1! Siga o Portal tpower. O treinamento ocorreu em um centro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20637,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/20636"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=20636"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/20636\/revisions"}],"predecessor-version":[{"id":20638,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/20636\/revisions\/20638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/20637"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=20636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=20636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=20636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}