{"id":20842,"date":"2026-03-13T09:16:47","date_gmt":"2026-03-13T12:16:47","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=20842"},"modified":"2026-03-13T09:16:47","modified_gmt":"2026-03-13T12:16:47","slug":"homem-que-torturou-e-matou-filha-de-5-anos-por-fazer-xixi-no-chao-e-encontrado-morto-em-presidio","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/homem-que-torturou-e-matou-filha-de-5-anos-por-fazer-xixi-no-chao-e-encontrado-morto-em-presidio\/","title":{"rendered":"Homem que torturou e matou filha de 5 anos por fazer xixi no ch\u00e3o \u00e9 encontrado morto em pres\u00eddio"},"content":{"rendered":"<p>O homem condenado por torturar e matar a pr\u00f3pria filha de cinco anos em Monte Santo de Minas, no Sul de Minas, foi encontrado morto na manh\u00e3 desta quarta-feira (11) no Complexo Penitenci\u00e1rio Nossa Senhora do Carmo, em Carmo do Parana\u00edba (MG). O crime pelo qual ele cumpria pena ocorreu em 2023.<\/p>\n<p>Segundo a Secretaria de Estado de Justi\u00e7a e Seguran\u00e7a P\u00fablica (Sejusp), policiais penais foram acionados por volta das 6h20 para atender o detento Adrian Juliano Martins Herculano. Ao chegarem \u00e0 cela, os agentes encontraram o preso pendurado por uma corda artesanal feita com len\u00e7ol e j\u00e1 sem sinais vitais.<\/p>\n<p>A dire\u00e7\u00e3o da unidade informou que foram adotadas as medidas administrativas necess\u00e1rias e instaurado um procedimento interno para apurar as circunst\u00e2ncias da morte. Os presos que dividiam a cela com Adrian dever\u00e3o ser ouvidos pelo Conselho Disciplinar do pres\u00eddio.<\/p>\n<p>De acordo com a secretaria, Adrian estava preso no complexo desde 14 de fevereiro de 2025 e tinha passagens pelo sistema prisional desde 2020. Ele cumpria pena ap\u00f3s ser condenado por matar e torturar a pr\u00f3pria filha em janeiro de 2023, em Monte Santo de Minas.<\/p>\n<p>Segundo a den\u00fancia do Minist\u00e9rio P\u00fablico de Minas Gerais (MPMG), o homem teria se irritado com a crian\u00e7a ap\u00f3s ela urinar no ch\u00e3o. Ele torturou a filha, a matou e depois ateou fogo no corpo na tentativa de escond\u00ea-lo.<\/p>\n<p>Adrian havia sido condenado a 33 anos de pris\u00e3o por homic\u00eddio triplamente qualificado e majorado, al\u00e9m dos crimes de oculta\u00e7\u00e3o e vilip\u00eandio de cad\u00e1ver.<\/p>\n<p>tpower &#8211; @portaltpower<br \/>\nConectado na not\u00edcia!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O homem condenado por torturar e matar a pr\u00f3pria filha de cinco anos em Monte Santo de Minas, no Sul de Minas, foi encontrado morto na manh\u00e3 desta quarta-feira (11) no Complexo Penitenci\u00e1rio Nossa Senhora do Carmo, em Carmo do Parana\u00edba (MG). O crime pelo qual ele cumpria pena ocorreu em 2023. Segundo a Secretaria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20843,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/20842"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=20842"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/20842\/revisions"}],"predecessor-version":[{"id":20844,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/20842\/revisions\/20844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/20843"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=20842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=20842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=20842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}