{"id":21591,"date":"2026-05-11T20:46:18","date_gmt":"2026-05-11T23:46:18","guid":{"rendered":"https:\/\/www.tpower.com.br\/site\/?p=21591"},"modified":"2026-05-11T20:46:18","modified_gmt":"2026-05-11T23:46:18","slug":"motorista-perde-controle-de-carro-e-tres-pessoas-ficam-feridas-na-br-369-em-alfenas","status":"publish","type":"post","link":"https:\/\/www.tpower.com.br\/site\/motorista-perde-controle-de-carro-e-tres-pessoas-ficam-feridas-na-br-369-em-alfenas\/","title":{"rendered":"Motorista perde controle de carro e tr\u00eas pessoas ficam feridas na BR-369, em Alfenas"},"content":{"rendered":"<p>Um carro saiu da pista e bateu contra um aclive \u00e0s margens da BR-369, no km 181, pr\u00f3ximo ao bairro Gaspar Lopes, em Alfenas. O acidente envolveu um Fiat Palio que seguia no sentido Alfenas\/Campos Gerais.<\/p>\n<p>Segundo o Corpo de Bombeiros, o motorista perdeu o controle da dire\u00e7\u00e3o, saiu da rodovia e colidiu em uma estrada de terra lateral. Quando as equipes chegaram ao local, os tr\u00eas ocupantes do ve\u00edculo j\u00e1 estavam fora do autom\u00f3vel.<\/p>\n<p>O condutor, de 31 anos, e um passageiro de 19 anos sofreram escoria\u00e7\u00f5es e ferimentos leves. Uma crian\u00e7a de 10 anos, que estava no banco traseiro, teve um corte contuso na cabe\u00e7a.<\/p>\n<p>As equipes realizaram o atendimento pr\u00e9-hospitalar, com avalia\u00e7\u00e3o e estabiliza\u00e7\u00e3o das v\u00edtimas. Em seguida, todos foram encaminhados ao Hospital Alzira Velano para avalia\u00e7\u00e3o m\u00e9dica.<\/p>\n<p>tpower &#8211; @portaltpower<br \/>\nConectado na not\u00edcia!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um carro saiu da pista e bateu contra um aclive \u00e0s margens da BR-369, no km 181, pr\u00f3ximo ao bairro Gaspar Lopes, em Alfenas. O acidente envolveu um Fiat Palio que seguia no sentido Alfenas\/Campos Gerais. Segundo o Corpo de Bombeiros, o motorista perdeu o controle da dire\u00e7\u00e3o, saiu da rodovia e colidiu em uma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21592,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/21591"}],"collection":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/comments?post=21591"}],"version-history":[{"count":1,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/21591\/revisions"}],"predecessor-version":[{"id":21593,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/posts\/21591\/revisions\/21593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media\/21592"}],"wp:attachment":[{"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/media?parent=21591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/categories?post=21591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tpower.com.br\/site\/wp-json\/wp\/v2\/tags?post=21591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}